{"id":3320,"date":"2024-06-22T08:06:17","date_gmt":"2024-06-22T08:06:17","guid":{"rendered":"https:\/\/cisanewsletter.com\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/"},"modified":"2024-06-22T08:09:35","modified_gmt":"2024-06-22T08:09:35","slug":"les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique","status":"publish","type":"post","link":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/","title":{"rendered":"Les \u00ab\u00a0deepfakes\u00a0\u00bb de l&rsquo;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Chaque \u00e9lection s&rsquo;accompagne g\u00e9n\u00e9ralement de toutes sortes de rumeurs, de propagande, de demi-v\u00e9rit\u00e9s et, parfois, de mensonges purs et simples. Dans le pass\u00e9, cela s&rsquo;est produit lorsque de telles sources de d\u00e9sinformation parvenaient \u00e0 \u00e9chapper \u00e0 l&rsquo;attention des gardiens des m\u00e9dias. Au cours de la derni\u00e8re d\u00e9cennie, les m\u00e9dias sociaux et l&rsquo;intelligence artificielle ont facilit\u00e9 la diffusion de ces sources potentielles de mensonges. S&rsquo;il y a une consolation, c&rsquo;est que m\u00eame les plateformes de m\u00e9dias sociaux voient maintenant la menace de leur utilisation comme courroies de transmission de la d\u00e9sinformation et de l&rsquo;information erron\u00e9e.<\/p>\n\n<p class=\"wp-block-paragraph\">Cette ann\u00e9e, pr\u00e8s de la moiti\u00e9 de la population mondiale votera, selon le National Democratic Institute, une organisation non gouvernementale am\u00e9ricaine \u00e0 but non lucratif dont la mission d\u00e9clar\u00e9e est de \u00ab\u00a0soutenir et renforcer les institutions d\u00e9mocratiques dans le monde entier gr\u00e2ce \u00e0 la participation des citoyens, \u00e0 l&rsquo;ouverture et \u00e0 la responsabilit\u00e9\u00a0\u00bb. Dans au moins 61 pays, pr\u00e8s de la moiti\u00e9 de la population mondiale se rendra aux urnes. Il s&rsquo;agit de huit des dix pays les plus peupl\u00e9s : Bangladesh, Br\u00e9sil, Inde, Indon\u00e9sie, Mexique, Pakistan, Russie et \u00c9tats-Unis.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;Union europ\u00e9enne organisera \u00e9galement des \u00e9lections au Parlement europ\u00e9en en juin. Au total, pr\u00e8s de 2 milliards de personnes, soit environ un quart des habitants de la plan\u00e8te, auront la possibilit\u00e9 de voter cette ann\u00e9e. Une quinzaine de ces \u00e9lections se tiendront en Afrique. Et comme c&rsquo;est le cas pour les \u00e9lections aux \u00c9tats-Unis, en Asie et en Europe, les \u00e9lections nationales dans les pays africains sont g\u00e9n\u00e9ralement entach\u00e9es de d\u00e9sinformation. Dans le cas de l&rsquo;Afrique, les menaces de d\u00e9sinformation sont encore plus probables, car la d\u00e9mocratie sur le continent a encore du mal \u00e0 s&rsquo;implanter solidement. Par cons\u00e9quent, la d\u00e9sinformation et la m\u00e9sinformation sont plus susceptibles de conduire \u00e0 des coups d&rsquo;\u00c9tat, des guerres, des troubles civils, des nettoyages ethniques et d&rsquo;autres atrocit\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">Le dictionnaire Oxford d\u00e9finit la d\u00e9sinformation comme une \u00ab\u00a0fausse information destin\u00e9e \u00e0 induire en erreur, en particulier la propagande diffus\u00e9e par une organisation gouvernementale \u00e0 l&rsquo;intention d&rsquo;une puissance rivale ou des m\u00e9dias\u00a0\u00bb. La d\u00e9finition de Wikip\u00e9dia est encore plus poignante : \u00ab\u00a0La d\u00e9sinformation est une fausse information diffus\u00e9e d\u00e9lib\u00e9r\u00e9ment pour tromper les gens.<\/p>\n\n<p class=\"wp-block-paragraph\">La d\u00e9sinformation est une activit\u00e9 orchestr\u00e9e et conflictuelle dans laquelle les acteurs utilisent des tromperies strat\u00e9giques et des tactiques de manipulation des m\u00e9dias pour atteindre des objectifs politiques, militaires ou commerciaux\u00a0\u00bb ; tandis que le dictionnaire Oxford d\u00e9finit la d\u00e9sinformation comme une \u00ab\u00a0information fausse ou inexacte, en particulier celle qui est d\u00e9lib\u00e9r\u00e9ment destin\u00e9e \u00e0 tromper\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">Selon Wikip\u00e9dia, \u00ab\u00a0la d\u00e9sinformation est une information incorrecte ou trompeuse. Il peut y avoir d\u00e9sinformation sans intention malveillante particuli\u00e8re ; la d\u00e9sinformation se distingue par le fait qu&rsquo;elle est d\u00e9lib\u00e9r\u00e9ment trompeuse et propag\u00e9e. La d\u00e9sinformation peut inclure des informations inexactes, incompl\u00e8tes, trompeuses ou fausses, ainsi que des v\u00e9rit\u00e9s s\u00e9lectives ou des demi-v\u00e9rit\u00e9s\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">Des preuves de d\u00e9sinformation ont d\u00e9j\u00e0 \u00e9t\u00e9 observ\u00e9es lors de certaines \u00e9lections qui ont eu lieu jusqu&rsquo;\u00e0 pr\u00e9sent dans diff\u00e9rentes parties du monde et se manifestent \u00e9galement dans les pays qui n&rsquo;ont pas encore organis\u00e9 d&rsquo;\u00e9lections cette ann\u00e9e. L&rsquo;IA et les m\u00e9dias sociaux sont des outils qui peuvent \u00eatre utilis\u00e9s \u00e0 bon ou \u00e0 mauvais escient lors d&rsquo;une \u00e9lection. En Inde, par exemple, l&rsquo;influence de l&rsquo;IA s&rsquo;est fait sentir de mani\u00e8re substantielle lors de la pr\u00e9paration des \u00e9lections en neuf phases qui se sont d\u00e9roul\u00e9es du 7 avril au 12 mai. Le Premier ministre Narendra Modi a eu recours \u00e0 l&rsquo;IA pour s&rsquo;adresser \u00e0 un public en hindi en utilisant l&rsquo;outil d&rsquo;IA cr\u00e9\u00e9 par le gouvernement, Bhashini, qui a ensuite \u00e9t\u00e9 traduit en tamoul en temps r\u00e9el. De l&rsquo;autre c\u00f4t\u00e9 de la fronti\u00e8re, au Pakistan, Amnesty International a autoris\u00e9 l&rsquo;homme politique emprisonn\u00e9 Imran Khan \u00e0 prendre la parole lors d&rsquo;un rassemblement. Les politiciens et les partis politiques profitent des m\u00e9dias sociaux pour diffuser des informations (d\u00e9clarations de presse, vid\u00e9os et photos d&rsquo;activit\u00e9s politiques, de r\u00e9alisations, etc.) \u00e0 peu de frais et \u00e0 grande \u00e9chelle, car ces plateformes ont une audience massive et instantan\u00e9e par rapport aux m\u00e9dias traditionnels.<\/p>\n\n<p class=\"wp-block-paragraph\">Toutefois, le c\u00f4t\u00e9 obscur de l&rsquo;IA et des m\u00e9dias sociaux commence \u00e0 susciter des inqui\u00e9tudes. Lors des \u00e9lections indiennes, par exemple, deux vid\u00e9os virales ont montr\u00e9 les stars de Bollywood Ranveer Singh et Aamir Khan faisant campagne pour le parti d&rsquo;opposition, le Congr\u00e8s, selon la BBC. Tous deux ont port\u00e9 plainte aupr\u00e8s de la police, affirmant qu&rsquo;il s&rsquo;agissait de deepfakes, r\u00e9alis\u00e9s sans leur consentement. Le 29 avril, le Premier ministre Modi s&rsquo;est \u00e9galement inqui\u00e9t\u00e9 de l&rsquo;utilisation de l&rsquo;IA pour d\u00e9former les discours de hauts responsables du parti au pouvoir, dont lui-m\u00eame.<\/p>\n\n<p class=\"wp-block-paragraph\">Le lendemain, la police a arr\u00eat\u00e9 deux personnes, l&rsquo;une du parti d&rsquo;opposition Aam Aadmi Party (AAP) et l&rsquo;autre du parti du Congr\u00e8s, en rapport avec une vid\u00e9o trafiqu\u00e9e du ministre de l&rsquo;int\u00e9rieur Amit Shah. De m\u00eame, les \u00ab\u00a0deepfakes\u00a0\u00bb de politiciens populaires d\u00e9c\u00e9d\u00e9s qui s&rsquo;adressent aux \u00e9lecteurs comme s&rsquo;ils \u00e9taient encore en vie sont devenus une tactique de campagne populaire en Inde. Il y a \u00e9galement eu une vid\u00e9o d&rsquo;une l\u00e9gislatrice de l&rsquo;opposition au Bangladesh &#8211; un pays conservateur \u00e0 majorit\u00e9 musulmane &#8211; portant un bikini.<\/p>\n\n<p class=\"wp-block-paragraph\">Selon TechTarget, Deepfake AI est \u00ab\u00a0un type d&rsquo;intelligence artificielle utilis\u00e9 pour cr\u00e9er des canulars convaincants en mati\u00e8re d&rsquo;images, d&rsquo;audio et de vid\u00e9o\u00a0\u00bb. Le terme d\u00e9crit \u00e0 la fois la technologie et le faux contenu qui en r\u00e9sulte, et est un portmanteau de \u00ab\u00a0deep learning\u00a0\u00bb (apprentissage profond) et \u00ab\u00a0fake\u00a0\u00bb (faux). Les deepfakes, note TechTarget, transforment souvent un contenu source existant o\u00f9 une personne est remplac\u00e9e par une autre. Ils cr\u00e9ent \u00e9galement des contenus enti\u00e8rement originaux dans lesquels une personne est repr\u00e9sent\u00e9e en train de faire ou de dire quelque chose qu&rsquo;elle n&rsquo;a pas fait ou dit.<\/p>\n\n<p class=\"wp-block-paragraph\">TechTarget met en garde : \u00ab\u00a0Le plus grand danger pos\u00e9 par les deepfakes est leur capacit\u00e9 \u00e0 diffuser de fausses informations qui semblent provenir de sources fiables. Par exemple, en 2022, une vid\u00e9o \u00ab\u00a0deepfake\u00a0\u00bb a \u00e9t\u00e9 publi\u00e9e montrant le pr\u00e9sident ukrainien Volodymyr Zelenskyy demandant \u00e0 ses troupes de se rendre.\u00a0\u00bb Elle ajoute que si les \u00ab\u00a0deepfakes\u00a0\u00bb constituent une menace s\u00e9rieuse, ils ont aussi des utilisations l\u00e9gitimes, comme les jeux vid\u00e9o audio et les divertissements, ainsi que les applications d&rsquo;assistance \u00e0 la client\u00e8le et de r\u00e9ponse aux appels, telles que le transfert d&rsquo;appel et les services de r\u00e9ceptionniste.<\/p>\n\n<p class=\"wp-block-paragraph\">Les \u00ab\u00a0deepfakes\u00a0\u00bb sont devenus monnaie courante dans les \u00e9lections am\u00e9ricaines. Un article r\u00e9dig\u00e9 par Emil Sayegh, pr\u00e9sident-directeur g\u00e9n\u00e9ral de Ntirety et publi\u00e9 le 14 mai 2024 par Forbes \u00e9num\u00e8re quelques exemples de deepfakes :<\/p>\n\n<p class=\"wp-block-paragraph\">1. Une vid\u00e9o manipul\u00e9e sur Twitter sugg\u00e9rant que le pr\u00e9sident Biden a incorrectement indiqu\u00e9 la dur\u00e9e de l&rsquo;occupation de Kiev par la Russie.<\/p>\n\n<p class=\"wp-block-paragraph\">2. Images manipul\u00e9es selon lesquelles la s\u00e9natrice Elizabeth Warren aurait pr\u00e9conis\u00e9 d&rsquo;interdire aux r\u00e9publicains de voter lors de l&rsquo;\u00e9lection pr\u00e9sidentielle de 2024.<\/p>\n\n<p class=\"wp-block-paragraph\">3. Modification de l&rsquo;audio sur TikTok transmettant faussement les menaces du pr\u00e9sident Biden de d\u00e9ployer des F-15 au Texas.<\/p>\n\n<p class=\"wp-block-paragraph\">4. Une modification de la vid\u00e9o faisant appara\u00eetre le vice-pr\u00e9sident Harris en \u00e9tat d&rsquo;\u00e9bri\u00e9t\u00e9 et absurde.<\/p>\n\n<p class=\"wp-block-paragraph\">5. Une photo en ligne g\u00e9n\u00e9r\u00e9e par l&rsquo;IA montrant faussement l&rsquo;ex-pr\u00e9sident Donald Trump en compagnie de Jeffrey Epstein et d&rsquo;une mineure.<\/p>\n\n<p class=\"wp-block-paragraph\">6. Des images cr\u00e9\u00e9es par l&rsquo;IA sur x (anciennement Twitter) repr\u00e9sentant faussement le pr\u00e9sident Biden en tenue militaire.<\/p>\n\n<p class=\"wp-block-paragraph\">7. Une publicit\u00e9 soutenue par un PAC utilisant abusivement l&rsquo;IA pour reproduire les critiques de Donald Trump \u00e0 l&rsquo;encontre de Kim Reynolds, gouverneur de l&rsquo;Iowa.<\/p>\n\n<p class=\"wp-block-paragraph\">8. Des portraits g\u00e9n\u00e9r\u00e9s par l&rsquo;IA de Donald Trump et Joe Biden dans un d\u00e9bat fictif sur Twitch.<\/p>\n\n<p class=\"wp-block-paragraph\">9. Une vid\u00e9o de la campagne de DeSantis avec des images fabriqu\u00e9es par l&rsquo;IA attaquant Donald Trump.<\/p>\n\n<p class=\"wp-block-paragraph\">10. Discours synth\u00e9tique sugg\u00e9rant que le pr\u00e9sident Biden a fait des commentaires sur l&rsquo;instabilit\u00e9 financi\u00e8re, susceptibles d&rsquo;inciter au chaos sur les march\u00e9s ou d&rsquo;induire en erreur les dirigeants d&rsquo;entreprise.<\/p>\n\n<p class=\"wp-block-paragraph\">Un article de Shanze Hasan publi\u00e9 le 6 juin 2024 sur <a href=\"http:\/\/www.brennancenter.org\/\">www.brennancenter.org<\/a> mentionne qu&rsquo;au d\u00e9but de l&rsquo;ann\u00e9e, des appels t\u00e9l\u00e9phoniques robotis\u00e9s g\u00e9n\u00e9r\u00e9s par l&rsquo;IA ont imit\u00e9 la voix du pr\u00e9sident Biden, ciblant les \u00e9lecteurs du New Hampshire et les d\u00e9courageant de voter lors des primaires. En outre, une image g\u00e9n\u00e9r\u00e9e par l&rsquo;IA repr\u00e9sentant faussement l&rsquo;ancien pr\u00e9sident Trump en compagnie du trafiquant sexuel Jeffrey Epstein et d&rsquo;une jeune fille a commenc\u00e9 \u00e0 circuler sur Twitter.<\/p>\n\n<p class=\"wp-block-paragraph\">En dehors des \u00c9tats-Unis, l&rsquo;article \u00e9num\u00e8re quelques autres incidents li\u00e9s aux \u00e9lections, tels que la circulation de faux en profondeur lors des \u00e9lections slovaques de l&rsquo;ann\u00e9e derni\u00e8re, qui ont diffam\u00e9 le chef d&rsquo;un parti politique et peut-\u00eatre contribu\u00e9 \u00e0 faire basculer l&rsquo;\u00e9lection en faveur de son adversaire pro-russe. Le 16 mars 2024, un reportage de la VOA sur la Slovaquie fait \u00e9tat d&rsquo;un faux enregistrement du chef du parti lib\u00e9ral du pays, qui discuterait de la modification des bulletins de vote et de l&rsquo;augmentation du prix de la bi\u00e8re. La VOA cite \u00e9galement une vid\u00e9o dans laquelle la pr\u00e9sidente pro-occidentale de la Moldavie apporte son soutien \u00e0 un parti politique ami de la Russie.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;article de Shanze Hasan, intitul\u00e9 \u00ab\u00a0The Effect of AI on Elections Around the World and What to Do About It\u00a0\u00bb, rappelle qu&rsquo;en janvier de cette ann\u00e9e, le gouvernement chinois a apparemment tent\u00e9 de d\u00e9ployer des \u00ab\u00a0deepfakes\u00a0\u00bb d&rsquo;IA pour s&rsquo;immiscer dans les \u00e9lections ta\u00efwanaises. L&rsquo;auteur a \u00e9galement observ\u00e9 qu&rsquo;une vague de contenus malveillants g\u00e9n\u00e9r\u00e9s par l&rsquo;IA apparaissait en Grande-Bretagne \u00e0 l&rsquo;approche des \u00e9lections, pr\u00e9vues pour le 4 juillet. Un deepfake montrait une pr\u00e9sentatrice de la BBC, Sarah Campbell, affirmant \u00e0 tort que le Premier ministre britannique Rishi Sunak faisait la promotion d&rsquo;une plateforme d&rsquo;investissement frauduleuse.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;article mentionne un cas o\u00f9 le principal candidat \u00e0 la pr\u00e9sidence en Indon\u00e9sie, un ancien g\u00e9n\u00e9ral, a utilis\u00e9 un dessin anim\u00e9 g\u00e9n\u00e9r\u00e9 par l&rsquo;IA pour s&rsquo;humaniser afin de s\u00e9duire les jeunes \u00e9lecteurs. Par ailleurs, au Belarus, l&rsquo;opposition en difficult\u00e9 du pays a pr\u00e9sent\u00e9 un \u00ab\u00a0candidat\u00a0\u00bb au parlement g\u00e9n\u00e9r\u00e9 par l&rsquo;IA. Le candidat &#8211; un chatbot qui se d\u00e9crit comme un homme de 35 ans originaire de Minsk &#8211; fait partie d&rsquo;une campagne de sensibilisation visant \u00e0 aider l&rsquo;opposition, dont beaucoup se sont exil\u00e9s, \u00e0 toucher les \u00e9lecteurs bi\u00e9lorusses.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c0 l&rsquo;approche des \u00e9lections pr\u00e9vues en 2025 \u00e0 Singapour, le pays a d\u00e9j\u00e0 commenc\u00e9 \u00e0 \u00eatre confront\u00e9 \u00e0 la menace des \u00ab\u00a0deepfakes\u00a0\u00bb de l&rsquo;IA. Channelnewsasia.com a rapport\u00e9 le 1er juin 2024 qu&rsquo;un message WhatsApp circule largement, affirmant que le nouveau Premier ministre Lawrence Wong a appel\u00e9 \u00e0 la tenue d&rsquo;\u00e9lections le 6 septembre 2024. Selon Channel News Asia, cependant, aucune \u00e9lection ne peut \u00eatre convoqu\u00e9e sans le comit\u00e9 de r\u00e9vision des circonscriptions \u00e9lectorales, qui, note-t-on, \u00ab\u00a0n&rsquo;a m\u00eame pas \u00e9t\u00e9 convoqu\u00e9 &#8211; du moins au 18 avril 2024 &#8211; et c&rsquo;est une \u00e9tape n\u00e9cessaire avant qu&rsquo;une \u00e9lection puisse \u00eatre convoqu\u00e9e\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">Les r\u00e9centes \u00e9lections en Afrique du Sud ont mis en \u00e9vidence l&rsquo;influence des m\u00e9dias sociaux et de l&rsquo;IA sur la politique africaine lorsque les g\u00e9ants de la technologie Meta (propri\u00e9taires de Facebook, WhatsApp, Instagram et Threads), ainsi que TikTok, X (anciennement Twitter) et Google ont refus\u00e9 de partager des plans \u00e9lectoraux d\u00e9taill\u00e9s et de s&rsquo;engager avec la soci\u00e9t\u00e9 civile sur leurs plans visant \u00e0 \u00e9touffer les fausses nouvelles et les propos intempestifs v\u00e9hicul\u00e9s par les m\u00e9dias sociaux, comme cela s&rsquo;est produit en 2021, qui a d\u00e9clench\u00e9 des violences ayant entra\u00een\u00e9 la mort de 300 personnes \u00e0 la suite d&rsquo;une affaire d&rsquo;outrage au tribunal contre l&rsquo;ancien pr\u00e9sident Jacob Zuma, qui est aujourd&rsquo;hui le chef du parti dissident uMkhonto we Sizwe (MK). Avant les \u00e9lections de cette ann\u00e9e, M. Zuma a \u00e9t\u00e9 disqualifi\u00e9 en raison d&rsquo;une condamnation ant\u00e9rieure \u00e0 une peine de prison pour outrage au tribunal. Ses partisans ont rejet\u00e9 la d\u00e9cision.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Si ces tribunaux, qui sont parfois captur\u00e9s, arr\u00eatent MK, ce sera l&rsquo;anarchie dans ce pays. Il y aura des \u00e9meutes comme vous n&rsquo;en avez jamais vu dans ce pays. Il n&rsquo;y aura pas d&rsquo;\u00e9lections\u00a0\u00bb, a d\u00e9clar\u00e9 Theeastafrican.co.ke, citant le dirigeant de MK, M. Visvin Reddy, dans une vid\u00e9o largement diffus\u00e9e sur les m\u00e9dias sociaux, dans laquelle il mena\u00e7ait le pays en mars 2024. M. Reddy est accus\u00e9 d&rsquo;incitation \u00e0 la violence publique, ainsi que d&rsquo;autres membres du parti MK, pour ce commentaire incendiaire. Par ailleurs, des posts sur les m\u00e9dias sociaux, dont une vid\u00e9o TikTok, ont montr\u00e9 des individus portant des chemises MK et brandissant des armes \u00e0 feu. En janvier 2024, plus de 60 personnes li\u00e9es \u00e0 MK ont \u00e9t\u00e9 inculp\u00e9es pour avoir foment\u00e9 des \u00e9meutes meurtri\u00e8res en 2021, selon le rapport.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Menaces de d\u00e9sinformation g\u00e9n\u00e9r\u00e9e par l&rsquo;IA en Afrique<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;Afrique est un continent potentiellement instable en mati\u00e8re de politique \u00e9lectorale et de d\u00e9mocratie. Plusieurs pays du continent s&rsquo;habituent aujourd&rsquo;hui \u00e0 l&rsquo;id\u00e9e de la d\u00e9mocratie, qui s&rsquo;installe peu \u00e0 peu. M\u00eame sans la menace de la d\u00e9sinformation, les \u00e9lections sont souvent un exercice tr\u00e8s tendu et fragile sur le continent. Si l&rsquo;on y ajoute la d\u00e9sinformation par l&rsquo;IA, la situation est encore plus d\u00e9licate. Cette \u00e9volution constitue une menace s\u00e9rieuse pour la d\u00e9mocratie du continent, d&rsquo;autant plus que certaines r\u00e9gions, comme le Sahel, optent pour des coups d&rsquo;\u00c9tat militaires et font preuve de tendances antid\u00e9mocratiques en annulant tous les progr\u00e8s d\u00e9mocratiques r\u00e9alis\u00e9s au cours des derni\u00e8res d\u00e9cennies par le biais d&rsquo;\u00e9lections nationales.<\/p>\n\n<p class=\"wp-block-paragraph\">Il convient \u00e9galement de noter que l&rsquo;Afrique est un continent tr\u00e8s religieux, conservateur et multiethnique avec un pot-pourri de cultures. Sans les \u00ab\u00a0deepfakes\u00a0\u00bb g\u00e9n\u00e9r\u00e9s par l&rsquo;IA, un homme s&rsquo;est assis \u00e0 la radio au Rwanda et a utilis\u00e9 des discours de haine pour d\u00e9clencher un g\u00e9nocide qui a entra\u00een\u00e9 le massacre de pr\u00e8s d&rsquo;un million de personnes. Sans la d\u00e9sinformation assist\u00e9e par l&rsquo;IA, des guerres auraient \u00e9t\u00e9 d\u00e9clench\u00e9es entre diff\u00e9rents groupes ethniques &#8211; certains pour le b\u00e9tail, d&rsquo;autres pour des rumeurs et des divisions ethniques et religieuses. Les deepfakes g\u00e9n\u00e9r\u00e9s par l&rsquo;IA pourraient aggraver la situation depuis que les t\u00e9l\u00e9phones portables et les m\u00e9dias sociaux sont devenus monnaie courante sur le continent. \u00c0 l&rsquo;\u00e8re num\u00e9rique, toute d\u00e9sinformation se r\u00e9pandra comme une tra\u00een\u00e9e de poudre et les cons\u00e9quences d\u00e9vastatrices seront sans commune mesure avec les \u00e9v\u00e9nements historiques ant\u00e9rieurs \u00e0 l&rsquo;IA.  <\/p>\n\n<p class=\"wp-block-paragraph\">Les grandes entreprises technologiques s&rsquo;attaquent aux \u00ab\u00a0deepfakes<\/p>\n\n<p class=\"wp-block-paragraph\">Les entreprises technologiques s&rsquo;efforcent toutefois de ma\u00eetriser le c\u00f4t\u00e9 obscur des contenus g\u00e9n\u00e9r\u00e9s par l&rsquo;IA afin de pr\u00e9venir la d\u00e9sinformation et la m\u00e9sinformation. TikTok, par exemple, a annonc\u00e9 en mai dernier qu&rsquo;il commencerait \u00e0 \u00e9tiqueter les contenus g\u00e9n\u00e9r\u00e9s par l&rsquo;I.A., selon CNN. Le r\u00e9seau d&rsquo;information international a \u00e9galement rapport\u00e9 que Meta a d\u00e9clar\u00e9 le mois dernier qu&rsquo;il commencerait \u00e0 \u00e9tiqueter le contenu de l&rsquo;IA. YouTube, a ajout\u00e9 CNN, a \u00e9galement introduit des r\u00e8gles obligeant les cr\u00e9ateurs \u00e0 r\u00e9v\u00e9ler quand les vid\u00e9os sont cr\u00e9\u00e9es par l&rsquo;I.A. afin qu&rsquo;un label puisse \u00eatre appliqu\u00e9. La soci\u00e9t\u00e9 X d&rsquo;Elon Musk n&rsquo;a toutefois pas annonc\u00e9 de projet d&rsquo;\u00e9tiquetage des contenus g\u00e9n\u00e9r\u00e9s par l&rsquo;intelligence artificielle. OpenAI, le cr\u00e9ateur de ChatGPT qui permet aux utilisateurs de cr\u00e9er \u00e0 leur tour des images g\u00e9n\u00e9r\u00e9es par l&rsquo;IA gr\u00e2ce \u00e0 son mod\u00e8le DALL-E, a d\u00e9clar\u00e9 le mois dernier qu&rsquo;il lancerait bient\u00f4t un outil permettant aux utilisateurs de d\u00e9tecter si une image a \u00e9t\u00e9 cr\u00e9\u00e9e par un robot. L&rsquo;entreprise a confirm\u00e9 qu&rsquo;elle lancerait un fonds de 2 millions de dollars avec Microsoft pour lutter contre les \u00ab\u00a0deepfakes\u00a0\u00bb qui peuvent \u00ab\u00a0tromper les \u00e9lecteurs et saper la d\u00e9mocratie\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">En Afrique, Dubawa, un projet du Centre pour l&rsquo;innovation et le d\u00e9veloppement du journalisme (CJID), a mis au point un chatbot, un outil d&rsquo;IA pour v\u00e9rifier les faits et d\u00e9manteler les \u00ab\u00a0deepfakes\u00a0\u00bb. Premiumtimesng.com cite Monsur Hussain, le responsable de l&rsquo;innovation au CJID, qui affirme que le Chatbot de Dubawa est d\u00e9velopp\u00e9 pour donner des r\u00e9ponses pr\u00e9cises et opportunes aux r\u00e9clamations ou aux questions. Il a pr\u00e9cis\u00e9 que cet outil avait acc\u00e8s \u00e0 des donn\u00e9es internet en temps r\u00e9el, contrairement \u00e0 d&rsquo;autres outils d&rsquo;IA tels que ChatGPT et MetaAI, qui tous deux \u00ab\u00a0n&rsquo;ont pas acc\u00e8s \u00e0 des donn\u00e9es internet en temps r\u00e9el\u00a0\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">  \u00ab\u00a0Le chatbot Dubawa est un outil d&rsquo;intelligence artificielle con\u00e7u pour r\u00e9pondre aux questions quotidiennes concernant la d\u00e9sinformation virale et la d\u00e9sinformation dans l&rsquo;\u00e9cosyst\u00e8me de l&rsquo;information\u00a0\u00bb, a r\u00e9pondu le chatbot lorsqu&rsquo;on l&rsquo;a interrog\u00e9 sur sa fonction. \u00ab\u00a0Il vise \u00e0 r\u00e9duire la diffusion de contenus nuisibles et trompeurs en ligne en proposant des r\u00e9sultats et des r\u00e9f\u00e9rences provenant de sources cr\u00e9dibles\u00a0\u00bb, a-t-il ajout\u00e9.<\/p>\n\n<p class=\"wp-block-paragraph\">Au Ghana, o\u00f9 les \u00e9lections auront lieu le 7 d\u00e9cembre 2024, l&rsquo;Autorit\u00e9 de cybers\u00e9curit\u00e9 du pays, selon ClassFMonline.com, s&rsquo;est engag\u00e9e \u00e0 collaborer avec les g\u00e9ants de la technologie pour lutter contre la diffusion de fausses informations et de d\u00e9sinformation en ligne, en particulier sur les plateformes de m\u00e9dias sociaux. L&rsquo;Autorit\u00e9 a expliqu\u00e9 qu&rsquo;\u00e0 l&rsquo;approche des \u00e9lections, le pays est susceptible d&rsquo;\u00eatre confront\u00e9 \u00e0 des campagnes de d\u00e9sinformation bas\u00e9es sur l&rsquo;IA en raison de la rapidit\u00e9 de la num\u00e9risation.<\/p>\n\n<p class=\"wp-block-paragraph\">D\u00e9crivant les \u00ab\u00a0deepfakes\u00a0\u00bb comme une activit\u00e9 \u00ab\u00a0malveillante\u00a0\u00bb lors de son intervention au symposium r\u00e9gional CSIRTS d&rsquo;Afrique de l&rsquo;Ouest \u00e0 Accra, le Dr Albert Antwi Boasiako, directeur g\u00e9n\u00e9ral de l&rsquo;Autorit\u00e9 de la cybers\u00e9curit\u00e9, a pr\u00e9venu qu'\u00a0\u00bbil y aura une s\u00e9rie de cyberattaques\u00a0\u00bb \u00e0 l&rsquo;approche de l&rsquo;\u00e9lection.<\/p>\n\n<p class=\"wp-block-paragraph\">Albert Antwi Boasiako a d\u00e9clar\u00e9 : \u00ab\u00a0Les criminels innovent dans leurs proc\u00e9d\u00e9s et il est probable que nous assisterons \u00e0 des campagnes de d\u00e9sinformation et de m\u00e9sinformation aliment\u00e9es par l&rsquo;IA. Cela nous complique un peu la t\u00e2che, mais nous travaillons avec les prestataires de services techniques &#8211; ceux qui poss\u00e8dent la plateforme.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Ils ont \u00e9galement des m\u00e9canismes pour nous attaquer. Ainsi, Facebook, Twitter, qui est maintenant X et d&rsquo;autres, nous nous engageons avec eux pour nous assurer qu&rsquo;\u00e0 l&rsquo;approche des \u00e9lections, nous serons en mesure de d\u00e9tecter et de pr\u00e9venir certains de ces probl\u00e8mes\u00a0\u00bb, a d\u00e9clar\u00e9 M. Boasiako.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque \u00e9lection s&rsquo;accompagne g\u00e9n\u00e9ralement de toutes sortes de rumeurs, de propagande, de demi-v\u00e9rit\u00e9s et, parfois, de mensonges purs et simples. Dans le pass\u00e9, cela s&rsquo;est produit lorsque de telles sources de d\u00e9sinformation parvenaient \u00e0 \u00e9chapper \u00e0 l&rsquo;attention des gardiens des m\u00e9dias. Au cours de la derni\u00e8re d\u00e9cennie, les m\u00e9dias sociaux et l&rsquo;intelligence artificielle ont facilit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[99,187,222],"tags":[216],"class_list":["post-3320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-analyse","category-la-science","tag-7eme-edition-2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les &quot;deepfakes&quot; de l&#039;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique - CISA NEWSLETTER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les &quot;deepfakes&quot; de l&#039;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique - CISA NEWSLETTER\" \/>\n<meta property=\"og:description\" content=\"Chaque \u00e9lection s&rsquo;accompagne g\u00e9n\u00e9ralement de toutes sortes de rumeurs, de propagande, de demi-v\u00e9rit\u00e9s et, parfois, de mensonges purs et simples. Dans le pass\u00e9, cela s&rsquo;est produit lorsque de telles sources de d\u00e9sinformation parvenaient \u00e0 \u00e9chapper \u00e0 l&rsquo;attention des gardiens des m\u00e9dias. Au cours de la derni\u00e8re d\u00e9cennie, les m\u00e9dias sociaux et l&rsquo;intelligence artificielle ont facilit\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/\" \/>\n<meta property=\"og:site_name\" content=\"CISA NEWSLETTER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61558173539135\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-22T08:06:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T08:09:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/AI-deepfake.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CISA EDITORIAL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CisaSocial\" \/>\n<meta name=\"twitter:site\" content=\"@CisaSocial\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CISA EDITORIAL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/\"},\"author\":{\"name\":\"CISA EDITORIAL\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/person\\\/a0e04c9eece75fa21ae2273867968b01\"},\"headline\":\"Les \u00ab\u00a0deepfakes\u00a0\u00bb de l&rsquo;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique\",\"datePublished\":\"2024-06-22T08:06:17+00:00\",\"dateModified\":\"2024-06-22T08:09:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/\"},\"wordCount\":3366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/AI-deepfake.jpg\",\"keywords\":[\"7\u00e8me \u00e9dition 2024\"],\"articleSection\":[\"Actualit\u00e9s\",\"ANALYSE\",\"La science\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/\",\"name\":\"Les \\\"deepfakes\\\" de l'IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique - CISA NEWSLETTER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/AI-deepfake.jpg\",\"datePublished\":\"2024-06-22T08:06:17+00:00\",\"dateModified\":\"2024-06-22T08:09:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/AI-deepfake.jpg\",\"contentUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/AI-deepfake.jpg\",\"width\":1000,\"height\":523,\"caption\":\"AI Deepfakes Threaten Africa\u2019s Democracy and Security\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/accueil-33\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00ab\u00a0deepfakes\u00a0\u00bb de l&rsquo;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#website\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/\",\"name\":\"CISA NEWSLETTER\",\"description\":\"Headlining West African News\",\"publisher\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cisanewsletter.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#organization\",\"name\":\"Centre for Intelligence & Security Analysis Ghana\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cisaghana.png\",\"contentUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cisaghana.png\",\"width\":1055,\"height\":1063,\"caption\":\"Centre for Intelligence & Security Analysis Ghana\"},\"image\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61558173539135\",\"https:\\\/\\\/x.com\\\/CisaSocial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/person\\\/a0e04c9eece75fa21ae2273867968b01\",\"name\":\"CISA EDITORIAL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g\",\"caption\":\"CISA EDITORIAL\"},\"sameAs\":[\"http:\\\/\\\/cisanewsletter.com\"],\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/author\\\/cisa-editorial\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \"deepfakes\" de l'IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique - CISA NEWSLETTER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \"deepfakes\" de l'IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique - CISA NEWSLETTER","og_description":"Chaque \u00e9lection s&rsquo;accompagne g\u00e9n\u00e9ralement de toutes sortes de rumeurs, de propagande, de demi-v\u00e9rit\u00e9s et, parfois, de mensonges purs et simples. Dans le pass\u00e9, cela s&rsquo;est produit lorsque de telles sources de d\u00e9sinformation parvenaient \u00e0 \u00e9chapper \u00e0 l&rsquo;attention des gardiens des m\u00e9dias. Au cours de la derni\u00e8re d\u00e9cennie, les m\u00e9dias sociaux et l&rsquo;intelligence artificielle ont facilit\u00e9 [&hellip;]","og_url":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/","og_site_name":"CISA NEWSLETTER","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61558173539135","article_published_time":"2024-06-22T08:06:17+00:00","article_modified_time":"2024-06-22T08:09:35+00:00","og_image":[{"width":1000,"height":523,"url":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/AI-deepfake.jpg","type":"image\/jpeg"}],"author":"CISA EDITORIAL","twitter_card":"summary_large_image","twitter_creator":"@CisaSocial","twitter_site":"@CisaSocial","twitter_misc":{"\u00c9crit par":"CISA EDITORIAL","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#article","isPartOf":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/"},"author":{"name":"CISA EDITORIAL","@id":"https:\/\/cisanewsletter.com\/#\/schema\/person\/a0e04c9eece75fa21ae2273867968b01"},"headline":"Les \u00ab\u00a0deepfakes\u00a0\u00bb de l&rsquo;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique","datePublished":"2024-06-22T08:06:17+00:00","dateModified":"2024-06-22T08:09:35+00:00","mainEntityOfPage":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/"},"wordCount":3366,"commentCount":0,"publisher":{"@id":"https:\/\/cisanewsletter.com\/#organization"},"image":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#primaryimage"},"thumbnailUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/AI-deepfake.jpg","keywords":["7\u00e8me \u00e9dition 2024"],"articleSection":["Actualit\u00e9s","ANALYSE","La science"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/","url":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/","name":"Les \"deepfakes\" de l'IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique - CISA NEWSLETTER","isPartOf":{"@id":"https:\/\/cisanewsletter.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#primaryimage"},"image":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#primaryimage"},"thumbnailUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/AI-deepfake.jpg","datePublished":"2024-06-22T08:06:17+00:00","dateModified":"2024-06-22T08:09:35+00:00","breadcrumb":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#primaryimage","url":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/AI-deepfake.jpg","contentUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/AI-deepfake.jpg","width":1000,"height":523,"caption":"AI Deepfakes Threaten Africa\u2019s Democracy and Security"},{"@type":"BreadcrumbList","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/les-deepfakes-de-lia-menacent-la-democratie-et-la-securite-en-afrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cisanewsletter.com\/fr\/index.php\/accueil-33\/"},{"@type":"ListItem","position":2,"name":"Les \u00ab\u00a0deepfakes\u00a0\u00bb de l&rsquo;IA menacent la d\u00e9mocratie et la s\u00e9curit\u00e9 en Afrique"}]},{"@type":"WebSite","@id":"https:\/\/cisanewsletter.com\/#website","url":"https:\/\/cisanewsletter.com\/","name":"CISA NEWSLETTER","description":"Headlining West African News","publisher":{"@id":"https:\/\/cisanewsletter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cisanewsletter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cisanewsletter.com\/#organization","name":"Centre for Intelligence & Security Analysis Ghana","url":"https:\/\/cisanewsletter.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cisanewsletter.com\/#\/schema\/logo\/image\/","url":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/08\/cisaghana.png","contentUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/08\/cisaghana.png","width":1055,"height":1063,"caption":"Centre for Intelligence & Security Analysis Ghana"},"image":{"@id":"https:\/\/cisanewsletter.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61558173539135","https:\/\/x.com\/CisaSocial"]},{"@type":"Person","@id":"https:\/\/cisanewsletter.com\/#\/schema\/person\/a0e04c9eece75fa21ae2273867968b01","name":"CISA EDITORIAL","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g","caption":"CISA EDITORIAL"},"sameAs":["http:\/\/cisanewsletter.com"],"url":"https:\/\/cisanewsletter.com\/fr\/index.php\/author\/cisa-editorial\/"}]}},"_links":{"self":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts\/3320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/comments?post=3320"}],"version-history":[{"count":1,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts\/3320\/revisions"}],"predecessor-version":[{"id":3321,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts\/3320\/revisions\/3321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/media\/3317"}],"wp:attachment":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/media?parent=3320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/categories?post=3320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/tags?post=3320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}