{"id":3294,"date":"2024-06-22T07:33:06","date_gmt":"2024-06-22T07:33:06","guid":{"rendered":"https:\/\/cisanewsletter.com\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/"},"modified":"2024-06-22T07:33:19","modified_gmt":"2024-06-22T07:33:19","slug":"leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine","status":"publish","type":"post","link":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/","title":{"rendered":"L&rsquo;effet d&rsquo;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Historique : La lutte contre le terrorisme au Mali<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Le Mali est aux prises avec le terrorisme et l&rsquo;insurrection dans les r\u00e9gions septentrionales du pays depuis une dizaine d&rsquo;ann\u00e9es. Les causes profondes de l&rsquo;insurrection sont les griefs historiques, les tensions ethniques et le d\u00e9bordement des groupes arm\u00e9s \u00e0 la suite de la crise libyenne de 2011. En 2012, les groupes d&rsquo;insurg\u00e9s et de djihadistes du nord du Mali se sont unifi\u00e9s, d\u00e9clenchant une crise sans pr\u00e9c\u00e9dent qui s&rsquo;est propag\u00e9e au centre du pays. Les troubles ont entra\u00een\u00e9 l&rsquo;intervention des troupes fran\u00e7aises soutenues par les forces tchadiennes, \u00e0 la demande du gouvernement malien. Le Mali a \u00e9galement sollicit\u00e9 l&rsquo;assistance d&rsquo;une mission de formation de l&rsquo;Union europ\u00e9enne pour renforcer les forces de s\u00e9curit\u00e9 maliennes. Un soutien suppl\u00e9mentaire a \u00e9t\u00e9 apport\u00e9 par les Nations unies, qui ont autoris\u00e9 la mise en place d&rsquo;une mission internationale de soutien au Mali sous conduite africaine (AFISMA). Cette mission de soutien s&rsquo;est rapidement transform\u00e9e en une mission dirig\u00e9e par les Nations unies, visant \u00e0 r\u00e9soudre le conflit. Malgr\u00e9 ces efforts, la paix n&rsquo;est toujours pas au rendez-vous.<\/p>\n\n<p class=\"wp-block-paragraph\">Op\u00e9rations militaires de la France : Les op\u00e9rations <strong>Serval (2013<\/strong> ) et <strong>Barkhane (2014)<\/strong> ont jou\u00e9 un r\u00f4le central dans le soutien aux efforts de lutte contre le terrorisme du Mali.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;<strong>op\u00e9ration Serval <\/strong>a \u00e9t\u00e9 lanc\u00e9e en r\u00e9ponse \u00e0 la r\u00e9solution 2085 du Conseil de s\u00e9curit\u00e9 des Nations unies, adopt\u00e9e le 20 d\u00e9cembre 2012, ainsi qu&rsquo;\u00e0 une demande officielle du gouvernement int\u00e9rimaire du Mali pour une assistance militaire fran\u00e7aise. Cette op\u00e9ration, qui visait \u00e0 lutter contre les militants islamistes, s&rsquo;est officiellement achev\u00e9e le 31 juillet 2014. L&rsquo;op\u00e9ration Barkhane, qui a d\u00e9but\u00e9 le 1er ao\u00fbt 2014, lui a succ\u00e9d\u00e9 avec un mandat plus large de lutte contre les combattants islamistes dans toute la r\u00e9gion du Sahel. L&rsquo;op\u00e9ration Barkhane visait \u00e0 apporter un soutien durable aux pays du Sahel dans leur lutte contre le terrorisme, en \u00e9tablissant une pr\u00e9sence militaire fran\u00e7aise plus permanente dans la r\u00e9gion avec des bases strat\u00e9giques \u00e0 Niamey, au Niger, et \u00e0 N&rsquo;Djamena, au Tchad.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;op\u00e9ration <strong>Barkhane<\/strong> est l&rsquo;op\u00e9ration militaire fran\u00e7aise la plus longue et la plus co\u00fbteuse depuis la Seconde Guerre mondiale. Elle a d\u00e9but\u00e9 en 2014 et a \u00e9t\u00e9 officiellement retir\u00e9e en ao\u00fbt 2023. Au d\u00e9but, l&rsquo;op\u00e9ration a \u00e9t\u00e9 couronn\u00e9e de succ\u00e8s et a permis d&rsquo;\u00e9tendre les bases permanentes \u00e0 d&rsquo;autres \u00c9tats du Sahel : Niger et Tchad. Malgr\u00e9 les premiers r\u00e9sultats obtenus en mati\u00e8re de renforcement des forces arm\u00e9es maliennes et d&rsquo;utilisation de technologies a\u00e9riennes et terrestres de pointe, l&rsquo;op\u00e9ration Serval n&rsquo;a finalement pas atteint ses objectifs. La pr\u00e9sence continue de groupes terroristes dans la r\u00e9gion et les pertes humaines consid\u00e9rables, avec des milliers de victimes civiles et militaires maliennes et plus de 2,5 millions de personnes d\u00e9plac\u00e9es, soulignent le succ\u00e8s limit\u00e9 de l&rsquo;op\u00e9ration.<\/p>\n\n<p class=\"wp-block-paragraph\">Plusieurs autres op\u00e9rations (la force conjointe du G5 Sahel) ont soutenu l&rsquo;\u00c9tat malien dans sa lutte contre le terrorisme. Toutefois, ce soutien important n&rsquo;a pas permis de r\u00e9tablir la stabilit\u00e9 au Mali, ni d&#8217;emp\u00eacher la menace terroriste de s&rsquo;\u00e9tendre au centre du Mali et \u00e0 l&rsquo;ensemble de la r\u00e9gion. La situation au Mali a entra\u00een\u00e9 des d\u00e9placements massifs de population vers les pays voisins, notamment la Mauritanie, avec des cons\u00e9quences \u00e9conomiques, sociales et humanitaires.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Lutte contre le terrorisme en Mauritanie  <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Avant 2011, la Mauritanie a subi dix-sept attaques terroristes, dont six ont \u00e9t\u00e9 perp\u00e9tr\u00e9es \u00e0 Nouakchott et revendiqu\u00e9es par le Groupe salafiste pour la pr\u00e9dication et le combat (GSPC) et Al-Qa\u00efda au Maghreb islamique (AQMI). Depuis, le pays n&rsquo;a pas connu d&rsquo;attentat terroriste.<\/p>\n\n<p class=\"wp-block-paragraph\">La Mauritanie a d\u00e9ploy\u00e9 des efforts consid\u00e9rables pour lutter contre le terrorisme et ses menaces. La phase initiale de sa strat\u00e9gie s&rsquo;est concentr\u00e9e sur le renforcement de la pr\u00e9sence de l&rsquo;\u00c9tat en fournissant de l&rsquo;aide et en garantissant des services sociaux de base afin de d\u00e9courager les gens de rejoindre les groupes arm\u00e9s. La deuxi\u00e8me phase a consist\u00e9 \u00e0 renforcer les mesures de s\u00e9curit\u00e9 pour neutraliser la menace djihadiste. Il s&rsquo;agissait notamment de cr\u00e9er des unit\u00e9s nomades de m\u00e9haristes (cavalerie chameli\u00e8re). La garde nationale m\u00e9hariste patrouille dans les zones recul\u00e9es \u00e0 la fronti\u00e8re du Mali pour assurer la surveillance et lutter contre les cellules terroristes actives. Les M\u00e9haristes sont \u00e9galement responsables de la militarisation de la fronti\u00e8re avec le Mali et de la surveillance des routes par le biais d&rsquo;une surveillance a\u00e9rienne et de postes de s\u00e9curit\u00e9 fixes.<\/p>\n\n<p class=\"wp-block-paragraph\">La troisi\u00e8me phase a adopt\u00e9 une approche th\u00e9ologique, \u00e9tablissant un dialogue politico-th\u00e9ologique entre th\u00e9ologiens et prisonniers. Cette strat\u00e9gie globale a permis de d\u00e9manteler plusieurs cellules terroristes et, par cons\u00e9quent, la Mauritanie n&rsquo;a connu aucune attaque terroriste depuis 2011.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Les effets des mesures antiterroristes du Mali sur le sol mauritanien<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">La fronti\u00e8re entre la Mauritanie et le Mali s&rsquo;\u00e9tend sur plus de 2 000 km. Les mesures antiterroristes prises par le Mali ont entra\u00een\u00e9 d&rsquo;importants dommages transfrontaliers le long des fronti\u00e8res de la Mauritanie.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>1. D\u00e9placements de populations et flux de r\u00e9fugi\u00e9s<\/em><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Le nord du Mali avait d\u00e9j\u00e0 connu un afflux important de personnes d\u00e9plac\u00e9es \u00e0 l&rsquo;int\u00e9rieur du pays en raison des menaces et des attaques du JNIM et de l&rsquo;ISGS. Selon les chiffres d&rsquo;octobre 2023, il y a 391 961 personnes d\u00e9plac\u00e9es au Mali et 104 324 r\u00e9fugi\u00e9s en Mauritanie.<\/p>\n\n<p class=\"wp-block-paragraph\">Les op\u00e9rations de lutte contre le terrorisme, en particulier celles qui font appel \u00e0 la force militaire, entra\u00eenent souvent le d\u00e9placement de populations locales. Des civils fuyant les violences dans le nord et le centre du Mali sont entr\u00e9s en Mauritanie. Cet afflux de r\u00e9fugi\u00e9s met \u00e0 rude \u00e9preuve les ressources et les infrastructures de la Mauritanie, ce qui entra\u00eene des probl\u00e8mes humanitaires.<\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9tablissement de camps de r\u00e9fugi\u00e9s pr\u00e8s de la fronti\u00e8re a entra\u00een\u00e9 une augmentation des tensions. Le camp de r\u00e9fugi\u00e9s de Mbera se trouve au sud-est de la Mauritanie, \u00e0 seulement 50 kilom\u00e8tres de la fronti\u00e8re avec le Mali. Selon les donn\u00e9es du Haut Commissariat des Nations unies pour les r\u00e9fugi\u00e9s (HCR) d&rsquo;octobre 2023, la Mauritanie accueille 112 021 r\u00e9fugi\u00e9s, dont 98,5 % de Maliens (108 095). Parmi ces r\u00e9fugi\u00e9s, 51% \u00e9taient des femmes et 54% des enfants (\u00e2g\u00e9s de 0 \u00e0 17 ans). 86 586 personnes ont \u00e9t\u00e9 enregistr\u00e9es dans le camp de Mbera, 1 313 l&rsquo;ont \u00e9t\u00e9 en dehors du camp et 10 553 \u00e9taient en attente d&rsquo;enregistrement. Au total, 1 268 personnes ont \u00e9t\u00e9 enregistr\u00e9es \u00e0 N\u00e9ma (sud-est de la Mauritanie) et 5 732 pr\u00e8s de N\u00e9ma. Cela fait de Mbera l&rsquo;un des plus grands camps de r\u00e9fugi\u00e9s d&rsquo;Afrique de l&rsquo;Ouest et le deuxi\u00e8me en termes de nombre de r\u00e9fugi\u00e9s maliens qu&rsquo;il abrite.<\/p>\n\n<p class=\"wp-block-paragraph\">En 2012, lorsque la guerre a \u00e9clat\u00e9 au Mali, des milliers de personnes ont fui vers la Mauritanie voisine \u00e0 la recherche d&rsquo;une s\u00e9curit\u00e9 que leur pays ne pouvait leur offrir. Dix ans plus tard, les r\u00e9fugi\u00e9s continuent d&rsquo;arriver au camp. Bien que la guerre ait officiellement pris fin il y a plusieurs ann\u00e9es, la poursuite des activit\u00e9s terroristes dans la r\u00e9gion oblige chaque ann\u00e9e des milliers de personnes \u00e0 fuir vers les pays voisins pour y vivre en paix. Ces camps n\u00e9cessitent des ressources importantes et des mesures de s\u00e9curit\u00e9, ce qui provoque parfois des frictions avec les communaut\u00e9s locales et les autorit\u00e9s mauritaniennes.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>2. Mouvements transfrontaliers des groupes terroristes<\/em><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Lorsque les forces maliennes et leurs partenaires internationaux s&rsquo;attaquent aux groupes terroristes, ces militants se d\u00e9placent souvent pour \u00e9viter d&rsquo;\u00eatre captur\u00e9s en traversant la Mauritanie voisine. Ce mouvement propage la menace terroriste au-del\u00e0 des fronti\u00e8res et conduit au <strong>recrutement et \u00e0 la radicalisation<\/strong> des populations locales en Mauritanie, ce qui d\u00e9stabilise et complique encore la s\u00e9curit\u00e9 r\u00e9gionale.<\/p>\n\n<p class=\"wp-block-paragraph\">Un avis aux voyageurs \u00e9mis par le Bureau am\u00e9ricain des affaires consulaires en juillet 2023 indique que le gouvernement mauritanien interdit certaines zones aux \u00e9trangers et \u00e0 la plupart des Mauritaniens. Ces \u00ab\u00a0zones de non circulation\u00a0\u00bb sont extr\u00eamement dangereuses en raison de leur proximit\u00e9 avec le Mali, o\u00f9 des groupes arm\u00e9s engag\u00e9s dans une insurrection active m\u00e8nent des attaques transfrontali\u00e8res en Mauritanie.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>3. Tensions diplomatiques<\/em><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Les op\u00e9rations transfrontali\u00e8res men\u00e9es par les forces maliennes et leurs alli\u00e9s \u00e0 la poursuite des insurg\u00e9s ont parfois d\u00e9bouch\u00e9 sur des op\u00e9rations qui ont p\u00e9n\u00e9tr\u00e9 par inadvertance sur le territoire mauritanien. Par exemple, dans le cadre de l&rsquo;op\u00e9ration Barkhane men\u00e9e par la France, les forces maliennes et alli\u00e9es ont parfois p\u00e9n\u00e9tr\u00e9 sur le territoire mauritanien, soit pour poursuivre des terroristes, soit pour des raisons logistiques. Ces incursions s\u00e9curitaires et militaires peuvent porter atteinte \u00e0 la souverainet\u00e9 de la Mauritanie et entra\u00eener des retomb\u00e9es diplomatiques.<\/p>\n\n<p class=\"wp-block-paragraph\">Des groupes djihadistes comme AQMI et l&rsquo;\u00c9tat islamique dans le Grand Sahara (ISGS) se d\u00e9placent \u00e9galement fr\u00e9quemment \u00e0 travers la fronti\u00e8re entre le Mali et la Mauritanie, ce qui donne lieu \u00e0 des poursuites et \u00e0 des escarmouches transfrontali\u00e8res. Des rapports sugg\u00e8rent que des militants fuyant la pression militaire au Mali ont parfois utilis\u00e9 la Mauritanie comme refuge temporaire ou voie de transit. Par cons\u00e9quent, la Mauritanie doit constamment adapter ses mesures de s\u00e9curit\u00e9 pour g\u00e9rer ces menaces. Cela implique souvent une militarisation accrue des fronti\u00e8res, ce qui peut entra\u00eener des affrontements accidentels avec les forces militaires maliennes qui p\u00e9n\u00e8trent par inadvertance sur le territoire mauritanien. La militarisation des fronti\u00e8res a plusieurs cons\u00e9quences pour les communaut\u00e9s locales situ\u00e9es le long des fronti\u00e8res et provoque des crises humanitaires.<\/p>\n\n<p class=\"wp-block-paragraph\">Pour g\u00e9rer ces probl\u00e8mes, les gouvernements malien et mauritanien ont renforc\u00e9 leur coop\u00e9ration, notamment en organisant des patrouilles conjointes et en \u00e9changeant des renseignements. Toutefois, l&rsquo;efficacit\u00e9 de ces accords est souvent mise \u00e0 l&rsquo;\u00e9preuve par la nature impr\u00e9visible des op\u00e9rations de lutte contre le terrorisme.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>CONCLUSION<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">La nature complexe des efforts du Mali en mati\u00e8re de lutte contre le terrorisme a grandement affect\u00e9 la Mauritanie, entra\u00eenant une multitude de d\u00e9fis humanitaires, s\u00e9curitaires et diplomatiques. Les strat\u00e9gies proactives de la Mauritanie, notamment son approche globale de la lutte contre le terrorisme et sa coop\u00e9ration avec le Mali, ont \u00e9t\u00e9 couronn\u00e9es de succ\u00e8s. La cr\u00e9ation d&rsquo;unit\u00e9s de m\u00e9haristes nomades (gardes nationaux m\u00e9haris) a non seulement renforc\u00e9 la s\u00e9curit\u00e9, mais a \u00e9galement contribu\u00e9 au d\u00e9mant\u00e8lement de plusieurs cellules terroristes le long de la fronti\u00e8re.<\/p>\n\n<p class=\"wp-block-paragraph\">Toutefois, le soutien international, la coop\u00e9ration r\u00e9gionale et les solutions innovantes restent n\u00e9cessaires pour s&rsquo;attaquer aux causes profondes du terrorisme dans la r\u00e9gion. Le renforcement des liens diplomatiques par la collaboration est essentiel pour att\u00e9nuer la menace et promouvoir la stabilit\u00e9 dans la r\u00e9gion du Sahel.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Source : Analyste CISA  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\">  R\u00c9F\u00c9RENCES<\/p>\n\n<p class=\"wp-block-paragraph\">Ch\u00e1vez, B. (2022, 19 septembre).  <em>Dans un camp de r\u00e9fugi\u00e9s mauritanien, les jeunes sont  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"> <em> guid\u00e9e de l&rsquo;analphab\u00e9tisme \u00e0 la formation en ligne<\/em>. Equal Times. <a href=\"https:\/\/www.equaltimes.org\/in-a-mauritanian-refugee-camp?lang=en#:~:text=In%20south%2Deast%20Mauritania%2C%20just,still%20arriving%20at%20the%20camp\">https:\/\/www.equaltimes.org\/in-a-mauritanian-refugee-camp?lang=en#:~:text=Dans %20Mauritania%%20just,still%%20at%%20just,still%<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Equipe de recherche : Virginie BAUDAIS, Moulaye EL ARBY (), <em>L&rsquo;impact de la crise malienne <\/em> sur le d\u00e9veloppement durable.  <\/p>\n\n<p class=\"wp-block-paragraph\"> <em> de s\u00e9curit\u00e9 en Mauritanie<\/em>, Plateforme d&rsquo;Analyse du Suivi et d&rsquo;Apprentissage au<\/p>\n\n<p class=\"wp-block-paragraph\">  Sahel, Production Pasas.  <a href=\"https:\/\/pasasminka.fr\">https:\/\/pasasminka.fr<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">GIZ\/UNHCR, &lsquo;<em>Comparative study on the socio-economic situation of refugees and host<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"> <em> dans la r\u00e9gion du Hodh Chargui, Mauritanie<\/em>, Rapport d&rsquo;analyse, 11 janvier,  <\/p>\n\n<p class=\"wp-block-paragraph\">                       2023.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Mauritanie &#8211; D\u00e9partement d&rsquo;\u00c9tat des \u00c9tats-Unis. (2023, 7 d\u00e9cembre).<\/em>  \u00c9tats-Unis  <\/p>\n\n<p class=\"wp-block-paragraph\">  D\u00e9partement d&rsquo;Etat.  <a href=\"https:\/\/www.state.gov\/reports\/country-reports-on-terrorism-2022\/mauritania\">https:\/\/www.state.gov\/reports\/country-reports-on-terrorism-2022\/mauritania<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><em>R\u00e9silience, adaptation et apprentissage : <\/em> Les <em>r\u00e9fugi\u00e9s maliens et leurs h\u00f4tes mauritaniens &#8211; Forced <\/em><em> Migration Review.<\/em> (n.d.). <a href=\"https:\/\/www.fmreview.org\/ndikintum-agmalha\/#:~:text=Mauritania%20currently%20hosts%2060%2C511%20refugees,%2C%20in%20south%2Deastern%20Mauritania\">https:\/\/www.fmreview.org\/ndikintum-agmalha\/#:~:%2060%%20refugees,%%2Deastern%<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Historique : La lutte contre le terrorisme au Mali Le Mali est aux prises avec le terrorisme et l&rsquo;insurrection dans les r\u00e9gions septentrionales du pays depuis une dizaine d&rsquo;ann\u00e9es. Les causes profondes de l&rsquo;insurrection sont les griefs historiques, les tensions ethniques et le d\u00e9bordement des groupes arm\u00e9s \u00e0 la suite de la crise libyenne de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_wp_convertkit_post_meta":{"form":"-1","landing_page":"0","tag":"0","restrict_content":"0"},"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[99,187,107],"tags":[216],"class_list":["post-3294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-analyse","category-le-monde","tag-7eme-edition-2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;effet d&#039;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine - CISA NEWSLETTER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;effet d&#039;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine - CISA NEWSLETTER\" \/>\n<meta property=\"og:description\" content=\"Historique : La lutte contre le terrorisme au Mali Le Mali est aux prises avec le terrorisme et l&rsquo;insurrection dans les r\u00e9gions septentrionales du pays depuis une dizaine d&rsquo;ann\u00e9es. Les causes profondes de l&rsquo;insurrection sont les griefs historiques, les tensions ethniques et le d\u00e9bordement des groupes arm\u00e9s \u00e0 la suite de la crise libyenne de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/\" \/>\n<meta property=\"og:site_name\" content=\"CISA NEWSLETTER\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61558173539135\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-22T07:33:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-22T07:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/mali-counter-terroism.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"CISA EDITORIAL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CisaSocial\" \/>\n<meta name=\"twitter:site\" content=\"@CisaSocial\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CISA EDITORIAL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/\"},\"author\":{\"name\":\"CISA EDITORIAL\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/person\\\/a0e04c9eece75fa21ae2273867968b01\"},\"headline\":\"L&rsquo;effet d&rsquo;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine\",\"datePublished\":\"2024-06-22T07:33:06+00:00\",\"dateModified\":\"2024-06-22T07:33:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/\"},\"wordCount\":2091,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mali-counter-terroism.webp\",\"keywords\":[\"7\u00e8me \u00e9dition 2024\"],\"articleSection\":[\"Actualit\u00e9s\",\"ANALYSE\",\"Le monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/\",\"name\":\"L'effet d'entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine - CISA NEWSLETTER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mali-counter-terroism.webp\",\"datePublished\":\"2024-06-22T07:33:06+00:00\",\"dateModified\":\"2024-06-22T07:33:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mali-counter-terroism.webp\",\"contentUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mali-counter-terroism.webp\",\"width\":700,\"height\":393,\"caption\":\"The Ripple Effect of Mali\u2019s Counterterrorism Efforts on Neighbouring Mauritania\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/accueil-33\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;effet d&rsquo;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#website\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/\",\"name\":\"CISA NEWSLETTER\",\"description\":\"Headlining West African News\",\"publisher\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cisanewsletter.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#organization\",\"name\":\"Centre for Intelligence & Security Analysis Ghana\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cisaghana.png\",\"contentUrl\":\"https:\\\/\\\/cisanewsletter.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cisaghana.png\",\"width\":1055,\"height\":1063,\"caption\":\"Centre for Intelligence & Security Analysis Ghana\"},\"image\":{\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61558173539135\",\"https:\\\/\\\/x.com\\\/CisaSocial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cisanewsletter.com\\\/#\\\/schema\\\/person\\\/a0e04c9eece75fa21ae2273867968b01\",\"name\":\"CISA EDITORIAL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g\",\"caption\":\"CISA EDITORIAL\"},\"sameAs\":[\"http:\\\/\\\/cisanewsletter.com\"],\"url\":\"https:\\\/\\\/cisanewsletter.com\\\/fr\\\/index.php\\\/author\\\/cisa-editorial\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'effet d'entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine - CISA NEWSLETTER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/","og_locale":"fr_FR","og_type":"article","og_title":"L'effet d'entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine - CISA NEWSLETTER","og_description":"Historique : La lutte contre le terrorisme au Mali Le Mali est aux prises avec le terrorisme et l&rsquo;insurrection dans les r\u00e9gions septentrionales du pays depuis une dizaine d&rsquo;ann\u00e9es. Les causes profondes de l&rsquo;insurrection sont les griefs historiques, les tensions ethniques et le d\u00e9bordement des groupes arm\u00e9s \u00e0 la suite de la crise libyenne de [&hellip;]","og_url":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/","og_site_name":"CISA NEWSLETTER","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61558173539135","article_published_time":"2024-06-22T07:33:06+00:00","article_modified_time":"2024-06-22T07:33:19+00:00","og_image":[{"width":700,"height":393,"url":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/mali-counter-terroism.webp","type":"image\/webp"}],"author":"CISA EDITORIAL","twitter_card":"summary_large_image","twitter_creator":"@CisaSocial","twitter_site":"@CisaSocial","twitter_misc":{"\u00c9crit par":"CISA EDITORIAL","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#article","isPartOf":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/"},"author":{"name":"CISA EDITORIAL","@id":"https:\/\/cisanewsletter.com\/#\/schema\/person\/a0e04c9eece75fa21ae2273867968b01"},"headline":"L&rsquo;effet d&rsquo;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine","datePublished":"2024-06-22T07:33:06+00:00","dateModified":"2024-06-22T07:33:19+00:00","mainEntityOfPage":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/"},"wordCount":2091,"commentCount":0,"publisher":{"@id":"https:\/\/cisanewsletter.com\/#organization"},"image":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#primaryimage"},"thumbnailUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/mali-counter-terroism.webp","keywords":["7\u00e8me \u00e9dition 2024"],"articleSection":["Actualit\u00e9s","ANALYSE","Le monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/","url":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/","name":"L'effet d'entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine - CISA NEWSLETTER","isPartOf":{"@id":"https:\/\/cisanewsletter.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#primaryimage"},"image":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#primaryimage"},"thumbnailUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/mali-counter-terroism.webp","datePublished":"2024-06-22T07:33:06+00:00","dateModified":"2024-06-22T07:33:19+00:00","breadcrumb":{"@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#primaryimage","url":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/mali-counter-terroism.webp","contentUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/06\/mali-counter-terroism.webp","width":700,"height":393,"caption":"The Ripple Effect of Mali\u2019s Counterterrorism Efforts on Neighbouring Mauritania"},{"@type":"BreadcrumbList","@id":"https:\/\/cisanewsletter.com\/fr\/index.php\/leffet-dentrainement-des-efforts-antiterroristes-du-mali-sur-la-mauritanie-voisine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cisanewsletter.com\/fr\/index.php\/accueil-33\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;effet d&rsquo;entra\u00eenement des efforts antiterroristes du Mali sur la Mauritanie voisine"}]},{"@type":"WebSite","@id":"https:\/\/cisanewsletter.com\/#website","url":"https:\/\/cisanewsletter.com\/","name":"CISA NEWSLETTER","description":"Headlining West African News","publisher":{"@id":"https:\/\/cisanewsletter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cisanewsletter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cisanewsletter.com\/#organization","name":"Centre for Intelligence & Security Analysis Ghana","url":"https:\/\/cisanewsletter.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cisanewsletter.com\/#\/schema\/logo\/image\/","url":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/08\/cisaghana.png","contentUrl":"https:\/\/cisanewsletter.com\/wp-content\/uploads\/2024\/08\/cisaghana.png","width":1055,"height":1063,"caption":"Centre for Intelligence & Security Analysis Ghana"},"image":{"@id":"https:\/\/cisanewsletter.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61558173539135","https:\/\/x.com\/CisaSocial"]},{"@type":"Person","@id":"https:\/\/cisanewsletter.com\/#\/schema\/person\/a0e04c9eece75fa21ae2273867968b01","name":"CISA EDITORIAL","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5b5396e9e972117bf9689978858ad932691d8aea505d34cd928f27f4a3d94d0?s=96&d=mm&r=g","caption":"CISA EDITORIAL"},"sameAs":["http:\/\/cisanewsletter.com"],"url":"https:\/\/cisanewsletter.com\/fr\/index.php\/author\/cisa-editorial\/"}]}},"_links":{"self":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts\/3294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/comments?post=3294"}],"version-history":[{"count":2,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts\/3294\/revisions"}],"predecessor-version":[{"id":3296,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/posts\/3294\/revisions\/3296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/media\/3291"}],"wp:attachment":[{"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/media?parent=3294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/categories?post=3294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cisanewsletter.com\/fr\/index.php\/wp-json\/wp\/v2\/tags?post=3294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}